{"id":22223,"date":"2022-04-07T17:27:31","date_gmt":"2022-04-07T17:27:31","guid":{"rendered":"http:\/\/skizoshoes.com\/product\/sneakers-oceans-by-pietro\/"},"modified":"2022-12-27T11:50:55","modified_gmt":"2022-12-27T11:50:55","slug":"sneakers-oceans-by-pietro","status":"publish","type":"product","link":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/","title":{"rendered":"Sneakers Ocean&#8217;s by Pietro"},"content":{"rendered":"<p>Todas as nossas solas t\u00eam de lado gravado \u201d FROM THE OCEAN \u201d<\/p>\n<p>Certifica\u00e7\u00f5es:<\/p>\n<ul>\n<li>GLOBAL RECYCLED STANDARD (GRS) 4.0<\/li>\n<li>PETA-APPROVED VEGAN<\/li>\n<li>GOTS Certification<\/li>\n<\/ul>\n<p>Ap\u00f3s a tua compra, come\u00e7aremos a fazer os teus sneakers \u00e0 m\u00e3o, e os receber\u00e1s nos pr\u00f3ximos 20 dias \u00fateis.<br \/>\nCUIDADOS: N\u00e3o podem ser lavados na m\u00e1quina ou submersos em \u00e1gua. Lava apenas com uma escova macia e \u00e1gua morna e sab\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano<\/p>\n<p>Lingua: <strong>Seatex Antracite<\/strong><br \/>\nGuarda Atacadores: <strong>Seatex Antracite<\/strong><br \/>\nLateral: <strong>Seatex Antracite<\/strong><br \/>\nTornozelo: <strong>Seatex Prata Met\u00e1lico<\/strong><br \/>\nAtacadores: <strong>Algod\u00e3o Reciclado Preto<\/strong><br \/>\nSola: <b>Borracha Caramelo Reciclada + 30% Casca de Arroz<\/b><\/p>\n<p><strong><em>S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina &#8220;CRIA OS TEUS&#8221;<\/em><\/strong><\/p>\n","protected":false},"featured_media":6582,"template":"","meta":{"content-type":"","_joinchat":[]},"product_brand":[],"product_cat":[141],"product_tag":[110],"class_list":["post-22223","product","type-product","status-publish","has-post-thumbnail","product_cat-sneakers-pt-pt","product_tag-sneakers-pt-pt","","first","instock","shipping-taxable","purchasable","product-type-variable"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\u00e1lico Atacadores: Algod\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina &quot;CRIA OS TEUS&quot;\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Skizo - From the Ocean\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sneakers Ocean\u2019s by Pietro - Skizo\" \/>\n\t\t<meta property=\"og:description\" content=\"Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\u00e1lico Atacadores: Algod\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina &quot;CRIA OS TEUS&quot;\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-04-07T17:27:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-12-27T11:50:55+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sneakers Ocean\u2019s by Pietro - Skizo\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\u00e1lico Atacadores: Algod\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina &quot;CRIA OS TEUS&quot;\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/shop\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/skizoshoes.com\\\/shop\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/categoria-produto\\\/sneakers-pt-pt\\\/#listItem\",\"name\":\"Sneakers\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/categoria-produto\\\/sneakers-pt-pt\\\/#listItem\",\"position\":3,\"name\":\"Sneakers\",\"item\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/categoria-produto\\\/sneakers-pt-pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/#listItem\",\"name\":\"Sneakers Ocean&#8217;s by Pietro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/shop\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/#listItem\",\"position\":4,\"name\":\"Sneakers Ocean&#8217;s by Pietro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/categoria-produto\\\/sneakers-pt-pt\\\/#listItem\",\"name\":\"Sneakers\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/#itempage\",\"url\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/\",\"name\":\"Sneakers Ocean\\u2019s by Pietro - Skizo\",\"description\":\"Sneakers Respir\\u00e1veis e Resistentes \\u00e0 \\u00c1gua, Personalizados e Feitos \\u00e0 M\\u00e3o em Portugal com Pl\\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\\u00e1lico Atacadores: Algod\\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\\u00e3o apenas uma inspira\\u00e7\\u00e3o, se quiseres podes criar na p\\u00e1gina \\\"CRIA OS TEUS\\\"\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/skizoshoes.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Ocean-\\u2013-Skizo-\\u2013-From-the-Ocean-2021-8-2-20_26_20.png\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/#mainImage\",\"width\":980,\"height\":980},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/produto\\\/sneakers-oceans-by-pietro\\\/#mainImage\"},\"datePublished\":\"2022-04-07T17:27:31+00:00\",\"dateModified\":\"2022-12-27T11:50:55+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/#organization\",\"name\":\"My WordPress\",\"description\":\"From the Ocean\",\"url\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/\",\"name\":\"Skizo\",\"description\":\"From the Ocean\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/skizoshoes.com\\\/pt-pt\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sneakers Ocean\u2019s by Pietro - Skizo","description":"Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\u00e1lico Atacadores: Algod\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina \"CRIA OS TEUS\"","canonical_url":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/pt-pt\/#listItem","position":1,"name":"Home","item":"https:\/\/skizoshoes.com\/pt-pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/shop\/#listItem","position":2,"name":"Shop","item":"https:\/\/skizoshoes.com\/shop\/","nextItem":{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/pt-pt\/categoria-produto\/sneakers-pt-pt\/#listItem","name":"Sneakers"},"previousItem":{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/pt-pt\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/pt-pt\/categoria-produto\/sneakers-pt-pt\/#listItem","position":3,"name":"Sneakers","item":"https:\/\/skizoshoes.com\/pt-pt\/categoria-produto\/sneakers-pt-pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/#listItem","name":"Sneakers Ocean&#8217;s by Pietro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/shop\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/#listItem","position":4,"name":"Sneakers Ocean&#8217;s by Pietro","previousItem":{"@type":"ListItem","@id":"https:\/\/skizoshoes.com\/pt-pt\/categoria-produto\/sneakers-pt-pt\/#listItem","name":"Sneakers"}}]},{"@type":"ItemPage","@id":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/#itempage","url":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/","name":"Sneakers Ocean\u2019s by Pietro - Skizo","description":"Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\u00e1lico Atacadores: Algod\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina \"CRIA OS TEUS\"","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/skizoshoes.com\/pt-pt\/#website"},"breadcrumb":{"@id":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/skizoshoes.com\/wp-content\/uploads\/2022\/04\/Ocean-\u2013-Skizo-\u2013-From-the-Ocean-2021-8-2-20_26_20.png","@id":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/#mainImage","width":980,"height":980},"primaryImageOfPage":{"@id":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/#mainImage"},"datePublished":"2022-04-07T17:27:31+00:00","dateModified":"2022-12-27T11:50:55+00:00"},{"@type":"Organization","@id":"https:\/\/skizoshoes.com\/pt-pt\/#organization","name":"My WordPress","description":"From the Ocean","url":"https:\/\/skizoshoes.com\/pt-pt\/"},{"@type":"WebSite","@id":"https:\/\/skizoshoes.com\/pt-pt\/#website","url":"https:\/\/skizoshoes.com\/pt-pt\/","name":"Skizo","description":"From the Ocean","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/skizoshoes.com\/pt-pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Skizo - From the Ocean","og:type":"article","og:title":"Sneakers Ocean\u2019s by Pietro - Skizo","og:description":"Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\u00e1lico Atacadores: Algod\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina &quot;CRIA OS TEUS&quot;","og:url":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/","article:published_time":"2022-04-07T17:27:31+00:00","article:modified_time":"2022-12-27T11:50:55+00:00","twitter:card":"summary","twitter:title":"Sneakers Ocean\u2019s by Pietro - Skizo","twitter:description":"Sneakers Respir\u00e1veis e Resistentes \u00e0 \u00c1gua, Personalizados e Feitos \u00e0 M\u00e3o em Portugal com Pl\u00e1stico do Oceano Lingua: Seatex Antracite Guarda Atacadores: Seatex Antracite Lateral: Seatex Antracite Tornozelo: Seatex Prata Met\u00e1lico Atacadores: Algod\u00e3o Reciclado Preto Sola: Borracha Caramelo Reciclada + 30% Casca de Arroz S\u00e3o apenas uma inspira\u00e7\u00e3o, se quiseres podes criar na p\u00e1gina &quot;CRIA OS TEUS&quot;"},"aioseo_meta_data":{"post_id":"22223","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-05-17 16:08:25","updated":"2025-06-05 16:57:30","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/skizoshoes.com\/pt-pt\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/skizoshoes.com\/shop\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/skizoshoes.com\/pt-pt\/categoria-produto\/sneakers-pt-pt\/\" title=\"Sneakers\">Sneakers<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSneakers Ocean\u2019s by Pietro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/skizoshoes.com\/pt-pt\/"},{"label":"Shop","link":"https:\/\/skizoshoes.com\/shop\/"},{"label":"Sneakers","link":"https:\/\/skizoshoes.com\/pt-pt\/categoria-produto\/sneakers-pt-pt\/"},{"label":"Sneakers Ocean&#8217;s by Pietro","link":"https:\/\/skizoshoes.com\/pt-pt\/produto\/sneakers-oceans-by-pietro\/"}],"jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/product\/22223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/media\/6582"}],"wp:attachment":[{"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=22223"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=22223"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=22223"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/skizoshoes.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=22223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}